        <!--[if lte IE 8]>
        <script charset="utf-8" type="text/javascript" src="//js.hsforms.net/forms/v2-legacy.js"></script>
        <![endif]-->
        <script>
            (function($) {
                $(document).ready(function() {
                    var target = $("#hs-form-fp");

                    function loadHs(cb) {
                        if (window.hs_loading) return;
                        if (window.hs_loaded) return cb();
                        window.hs_loading = true;
                        $.ajaxSetup({
                            cache: true
                        });
                        $.getScript('//js.hsforms.net/forms/v2.js', function() {
                            window.hs_loaded = true;
                            window.hs_loading = false;
                            cb();
                        });
                    }

                    function createHsForm() {
                        loadHs(function() {
                            if (target.find('form')[0]) return;
                            hbspt.forms.create({
                                css: "",
                                portalId: "1983423",
                                formId: "b113e7e5-30f4-482f-a470-59371ac2df11",
                                target: "#hs-form-fp",
                                onFormSubmit: function() {
                                    setTimeout(function() {
                                        jQuery(".hubspot-form-wrap-load").hide();
                                        jQuery(".hubspot-form-wrap-success").show();
                                    }, 300);
                                    window.dataLayer.push({
                                        event: "GTMevent",
                                        eventCategory: "overlay",
                                        eventAction: "form-submission",
                                        eventLabel: $("#free-preview-modal .modal__header .modal__title").text(),
                                        page_location: window.location.href,
                                        page_path: window.location.pathname
                                    });
                                }
                            });
                        });
                    }

                    if ($('body').hasClass('page-template-page-toolkit')) {
                        !target.children().length && target.append('<div class="simple-preloader"></div>');
                        $('.modal__open').on('click', createHsForm);
                    } else createHsForm()
                });
            })(jQuery);
        </script>
            <!--[if lte IE 8]>
        <script charset="utf-8" type="text/javascript" src="//js.hsforms.net/forms/v2-legacy.js"></script>
        <![endif]-->
        <script>
            (function($) {
                $(document).ready(function() {
                    var target = $("#hs-form-fp");

                    function loadHs(cb) {
                        if (window.hs_loading) return;
                        if (window.hs_loaded) return cb();
                        window.hs_loading = true;
                        $.ajaxSetup({
                            cache: true
                        });
                        $.getScript('//js.hsforms.net/forms/v2.js', function() {
                            window.hs_loaded = true;
                            window.hs_loading = false;
                            cb();
                        });
                    }

                    function createHsForm() {
                        loadHs(function() {
                            if (target.find('form')[0]) return;
                            hbspt.forms.create({
                                css: "",
                                portalId: "1983423",
                                formId: "b113e7e5-30f4-482f-a470-59371ac2df11",
                                target: "#hs-form-fp",
                                onFormSubmit: function() {
                                    setTimeout(function() {
                                        jQuery(".hubspot-form-wrap-load").hide();
                                        jQuery(".hubspot-form-wrap-success").show();
                                    }, 300);
                                    window.dataLayer.push({
                                        event: "GTMevent",
                                        eventCategory: "overlay",
                                        eventAction: "form-submission",
                                        eventLabel: $("#free-preview-modal .modal__header .modal__title").text(),
                                        page_location: window.location.href,
                                        page_path: window.location.pathname
                                    });
                                }
                            });
                        });
                    }

                    if ($('body').hasClass('page-template-page-toolkit')) {
                        !target.children().length && target.append('<div class="simple-preloader"></div>');
                        $('.modal__open').on('click', createHsForm);
                    } else createHsForm()
                });
            })(jQuery);
        </script>
    {"id":64247,"date":"2020-09-14T11:15:11","date_gmt":"2020-09-14T11:15:11","guid":{"rendered":"https:\/\/multiacademstg.wpengine.com\/27001academy\/iso-27001-documentation-toolkit-new-app\/"},"modified":"2026-06-29T16:09:13","modified_gmt":"2026-06-29T16:09:13","slug":"kit-documentazione-iso-27001","status":"publish","type":"page","link":"https:\/\/advisera.com\/27001academy\/it\/kit-documentazione-iso-27001\/","title":{"rendered":"Kit Documentazione ISO 27001"},"content":{"rendered":"<div id=\"pl-64247\"  class=\"panel-layout\" ><div id=\"pg-64247-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-64247-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-64247-0-0-0\" class=\"so-panel widget widget_list-with-infos-widget panel-first-child\" data-index=\"0\" ><div id=\"overview\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-list-with-infos-widget so-widget-list-with-infos-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"list-with-info__section\">\n  <div class=\"l-section\">\n    <div class=\"a-row list-with-info__head\">\n      <h1>KIT DOCUMENTAZIONE ISO 27001 - IMPLEMENTAZIONE BASATA SULL\u2019IA<\/h1>\n      <p>Raggiungi pi\u00f9 rapidamente la conformit\u00e0 alla ISO 27001 con documenti strutturati, guida esperta e personalizzazione basata sull\u2019IA.<\/p>\n    <\/div>\n    <div class=\"a-row list-with-info__content\">\n\n      <div class=\"list-with-info\">\t  \t \n\t\t                <div class=\"list-with-info__title\">\n          <h2 class=\"heading-alt\">Guida passo dopo passo con <span style=\"color: #1a7bb1;\">ASSISTENZA DAL VIVO DI UN ESPERTO<\/span><\/h2>\n\n        <\/div>\n        <ul class=\"list-with-info__list\">\n                                    <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>45 modelli di documenti <\/strong>adattati all\u2019ultima revisione 2022 della norma \u2013 accesso illimitato a tutti i documenti richiesti per la certificazione ISO 27001, oltre ai documenti non obbligatori di uso comune<\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Politiche, procedure, piani e moduli modificabili in MS Word e MS Excel, che puoi adattare alle esigenze della tua azienda.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>Crea e personalizza documenti con Experta AI Copilot <\/strong>\u2014 rispondi a domande guidate e genera pi\u00f9 rapidamente documenti specifici per la tua azienda<\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Il modulo Create Documents di Experta ti aiuta a personalizzare i modelli Advisera comprovati tramite una procedura guidata basata sull\u2019IA \u2014 inserendo direttamente nel documento scaricabile i dati della tua azienda, i ruoli, i processi e le tecnologie che utilizzi.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p>Accesso ai\u00a0<strong>video tutorial\u00a0<\/strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;(In inglese)&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:12801,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0,&quot;15&quot;:&quot;Arial&quot;,&quot;16&quot;:11}\">(In inglese)<\/span><\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Video che ti aiuteranno a compilare i documenti pi\u00f9 importanti utilizzando dati reali: quello che devi mantenere, cosa puoi cambiare e cosa puoi eliminare.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>Assistenza per email\u00a0<\/strong><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;(In inglese)&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:12801,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0,&quot;15&quot;:&quot;Arial&quot;,&quot;16&quot;:11}\">(In inglese)<\/span><\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Risponderemo alle tue domande entro 1 giorno lavorativo.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>Revisione di un documento da parte di un esperto<\/strong><\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Dopo avere compilato il documento, potrai inviarcelo per farcelo esaminare, e ti daremo i nostri commenti su cosa debba essere migliorato per renderlo conforme alle norme.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>Un\u2019ora di consulenza online<\/strong><br \/>\ncon un esperto di ISO 27001 <span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;(In inglese)&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:12801,&quot;3&quot;:{&quot;1&quot;:0},&quot;12&quot;:0,&quot;15&quot;:&quot;Arial&quot;,&quot;16&quot;:11}\">(In inglese)<\/span><\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Il nostro esperto ti parler\u00e0 via Zoom, MS Teams, o per telefono, a un orario che sia comodo per te, per discutere su come risolvere qualsiasi problema che ti si dovesse presentare durante l\u2019implementazione; l\u2019esperto di dar\u00e0 inoltre delle indicazioni sulle fasi successive del tuo progetto.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                                                <li>\n                <span class=\"info-list__check\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#check\"><\/use>\n    <\/svg>\n    <\/span>\n                <p><strong>Programma di formazione sulla consapevolezza della sicurezza<\/strong><\/p>\n\n                                  <div class=\"tooltip--wrapper\">\n                    <span class=\"tooltip--icon\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#info\"><\/use>\n    <\/svg>\n    <\/span>\n                    <div class=\"tooltip--text\"><p>Tre mesi di accesso gratuito a un programma completo di formazione sulla consapevolezza della sicurezza.<\/p>\n<\/div>\n                  <\/div>\n                              <\/li>\n                              <\/ul>\n        <div class=\"additional-text\">\n          <p>Completamente ottimizzato per<br \/>\n<strong>piccole e medie<\/strong> imprese<\/p>\n\n        <\/div>\n      <\/div>\n\n      <div class=\"list-with-info__video-wrapper\">\n        <div class=\"list-with-info__video\">\n          <div class=\"list-with-info__video-frame\">\n                            <img decoding=\"async\" class=\"lazy-load-c\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" width=\"400\" height=\"240\" data-src=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/images\/newsite\/empty-laptop-frame.png\" alt=\"video thumbnail\">\n              <a href=\"https:\/\/player.vimeo.com\/video\/260977098\" class=\"wplightbox\" data-width=\"1280\" data-height=\"720\" data-is-btn=\"true\" target=\"_blank\" rel=\"noopener\">\n                <img decoding=\"async\" class=\"list-with-info__video-img lazy-load-c\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/10\/iso27001-kit-documentazione-video.png\" alt=\"How do the toolkits work?\">\n              <\/a>\n              \n          <\/div>\n          <div class=\"pricing__text list-with-info__dual-purchase-enabled\">\n            <div class=\"pricing__language\">\n              <div class=\"pricing__language-text\">\n                <p>LINGUA DEL KIT DOCUMENTAZIONE<\/p>\n                                  <div class=\"dropdown\">\n                    <button class=\"dropbtn\">Italian     <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#angle-arrow-down\"><\/use>\n    <\/svg>\n    <\/button>\n                    <div class=\"dropdown-content\">\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/\">English<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/de\/\">Deutsch<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/es\/\">Espa\u00f1ol<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/nl\/\">Nederlands<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/fr\/\">Fran\u00e7ais<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/pt-br\/\">Portugu\u00eas<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/ja\/\">\u65e5\u672c\u8a9e<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/hr\/\">Hrvatski<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/bg\/\">\u0411\u044a\u043b\u0433\u0430\u0440\u0441\u043a\u0438<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/pl\/\">Polski<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/sr\/\">\u0441\u0440\u043f\u0441\u043a\u0438<\/a>\n                                              <a href=\"https:\/\/advisera.com\/27001academy\/zh-cn\/\">\u7b80\u4f53\u4e2d\u6587<\/a>\n                                          <\/div>\n                  <\/div>\n                              <\/div>\n                          <\/div>\n\n                        <div class=\"dual-purchase-options\">\n              <div class=\"dual-purchase-option is-selected\" data-option=\"option_1\" data-url=\"https:\/\/securecheckout.advisera.com\/b\/00w3cv5HL8pi2GTcdSgjC1w?locale=it&#038;CURRENCY=USD\">\n                <div class=\"dual-purchase-radio\"><span class=\"radio-indicator\"><\/span><\/div>\n                <div class=\"dual-purchase-content\">\n                  <div class=\"dual-purchase-text\">\n                    <strong class=\"dual-purchase-heading\">Accesso a tutti i 45 documenti del toolkit in una sola volta<\/strong>\n                    <span class=\"dual-purchase-description\">Accedi subito al toolkit completo per la piena conformit\u00e0 ISO 27001.<\/span>\n                  <\/div>\n                  <div class=\"dual-purchase-pricing\">\n                    <div class=\"price-wrap\">\n                                              <span class=\"currency-text caption-2\">US<\/span>\n                                            <span class=\"dual-purchase-price\">$897<\/span>\n                                          <\/div>\n                                          <span class=\"dual-purchase-price-desc\">pagamento unico<\/span>\n                                      <\/div>\n                <\/div>\n              <\/div>\n              <div class=\"dual-purchase-option\" data-option=\"option_2\" data-url=\"https:\/\/securecheckout.advisera.com\/b\/8x2dR9fildJC2GTem0gjC1v?locale=it&#038;CURRENCY=USD\">\n                <div class=\"dual-purchase-radio\"><span class=\"radio-indicator\"><\/span><\/div>\n                <div class=\"dual-purchase-content\">\n                  <div class=\"dual-purchase-text\">\n                    <strong class=\"dual-purchase-heading\">Accesso a 3 documenti al mese<\/strong>\n                    <span class=\"dual-purchase-description\">Scegli solo i documenti di cui hai bisogno. Nessun impegno, disdici in qualsiasi momento.<\/span>\n                  <\/div>\n                  <div class=\"dual-purchase-pricing\">\n                    <div class=\"price-wrap\">\n                                              <span class=\"currency-text caption-2\">US<\/span>\n                                            <span class=\"dual-purchase-price\">$100<\/span>\n                                          <\/div>\n                                          <span class=\"dual-purchase-price-desc\">al mese<\/span>\n                                      <\/div>\n                <\/div>\n              <\/div>\n            <\/div>\n            \n                          <a href=\"https:\/\/securecheckout.advisera.com\/b\/00w3cv5HL8pi2GTcdSgjC1w?locale=it&#038;CURRENCY=USD\" class=\"pricing__button push-campaign-utms\" rel=\"noopener noreferrer nofollow\" data-button-inner-text=\"Purchase button - top\" data-is-btn=\"true\">PROCEDI CON IL PAGAMENTO<\/a>\n            \n            \n                            <a href=\"https:\/\/platform.advisera.com\/register\/?product=toolkit&amp;language=IT&amp;country=ALL&amp;framework=ISO 27001&amp;currency=USD\" data-button-inner-text=\"Free trial button - top\" class=\"pricing__button_demo push-campaign-utms\" target=\"\" rel=\"noopener noreferrer nofollow\">\n                    Prova gratuita\n                <\/a>\n            \n            <div class=\"pricing__countries\">\n              <div><p>CLIENTI DA <strong>107 PAESI<\/strong><\/p>\n<\/div>\n              <div class=\"pricing__paycards\">\n                <img decoding=\"async\" class=\"lazy-load-c\" width=\"155\" height=\"21\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/images\/newsite\/cards4.png\" alt=\"payment cards\">\n              <\/div>\n            <\/div>\n            <div class=\"pricing__lock\">\n              <img decoding=\"async\" class=\"lazy-load-c\" width=\"17\" height=\"26\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/images\/newsite\/lock-icon.png\" alt=\"security key image\">\n              <span>Fatturazione online sicura al 100%<br>AES-256bit SSL safe<\/span>\n            <\/div>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section><\/div><\/div><\/div><script id=\"toolkit-docs-genered\">window.toolkit_docs = {\n                tabs:[[{\"t\":\"Procedura per il controllo dei documenti e delle registrazioni\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_Procedura_per_il_controllo_dei_documenti_e_delle_registrazioni_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Procedura per l'identificazione dei requisiti\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Piano_di_progetto_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Elenco dei requisiti legali, normativi, contrattuali e di altro tipo\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Procedura_per_l_identificazione_dei_requisiti_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Documento sul campo di applicazione del SGSI\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Documento_sul_campo_di_applicazione_del_SGSI_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di sicurezza delle informazioni\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_ISO_27001)_01_Politica_di_sicurezza_delle_informazioni_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Piano di formazione e sensibilizzazione\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Piano_di_formazione_e_sensibilizzazione_(Anteprima).pdf\",\"downloadable\":true,\"active\":\"\"},{\"t\":\"Rapporto di misurazione\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Rapporto_di_misurazione_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Verbale del riesame di direzione\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_02_Verbale_del_riesame_di_direzione_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Procedura di azione correttiva\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Procedura_di_azione_correttiva_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Modulo di azione correttiva\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_02_Appendice_1_\u2013_Modulo_di_azione_correttiva_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"}],[{\"t\":\"Metodologia per la valutazione e il trattamento dei rischi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Metodologia_per_la_valutazione_e_il_trattamento_dei_rischi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Tabella di valutazione dei rischi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_02_Appendice_1_-_Tabella_di_valutazione_dei_rischi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Tabella di trattamento dei rischi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_03_Appendice_2_-_Tabella_di_trattamento_dei_rischi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Rapporto di valutazione e trattamento dei rischi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_04_Appendice_3_-_Rapporto_di_valutazione_e_trattamento_dei_rischi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Dichiarazione di applicabilit\u00e0 \",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_ISO_27001)_01_Dichiarazione_di_applicabilita_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Piano di trattamento dei rischi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Piano_di_trattamento_dei_rischi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"}],[{\"t\":\"Politica di sicurezza TI\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Politica_di_sicurezza_TI_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di scrivania e schermo puliti\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_02_Politica_di_scrivania_e_schermo_puliti_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica su dispositivi mobili, telelavoro e lavoro da casa\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_03_Politica_su_dispositivi_mobili_telelavoro_e_lavoro_da_casa_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica Bring Your Own Device (BYOD)\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_04_Politica_Bring_Your_Own_Device_(BYOD)_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Procedure per lavorare in aree sicure\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_05_Procedure_per_lavorare_in_aree_sicure_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di classificazione delle informazioni\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_06_Politica_di_classificazione_delle_informazioni_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Inventario degli asset\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_07_Inventario_degli_asset_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Procedure di sicurezza per il reparto TI\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_08_Procedure_di_sicurezza_per_il_reparto_TI_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di gestione dei cambiamenti\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_09_Politica_di_gestione_dei_cambiamenti_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di backup\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_10_Politica_di_backup_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di trasferimento delle informazioni\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_11_Politica_di_trasferimento_delle_informazioni_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di smaltimento e distruzione\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_12_Politica_di_smaltimento_e_distruzione_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica sull'uso della cifratura\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_13_Politica_sull_uso_della_cifratura_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di controllo degli accessi\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_14_Politica_di_controllo_degli_accessi_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica sulle password\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_15_Politica_sulle_password_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di sviluppo sicuro\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_16_Politica_di_sviluppo_sicuro_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Specifiche dei requisiti del sistema informativo\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_17_Appendice_1_\u2013_Specifiche_dei_requisiti_del_sistema_informativo_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Politica di sicurezza dei fornitori\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_18_Politica_di_sicurezza_dei_fornitori_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Clausole di sicurezza per fornitori e partner\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_19_Clausole_di_sicurezza_per_fornitori_e_partner_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Procedura di gestione degli incidenti\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_20_Procedura_di_gestione_degli_incidenti_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Registro degli incidenti\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_21_Appendice_1_\u2013_Registro_degli_incidenti_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Dichiarazione di riservatezza\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_23_Dichiarazione_di_riservatezza_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Dichiarazione di accettazione dei documenti del SGSI\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_24_Dichiarazione_di_accettazione_dei_documenti_del_SGSI_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"}],[{\"t\":\"Piano di disaster recovery\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_22_Piano_di_disaster_recovery_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"}],[{\"t\":\"Procedura per l'audit interno\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_01_Procedura_per_l_audit_interno_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Programma annuale degli audit interni\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_02_Appendice_1_\u2013_Programma_annuale_degli_audit_internI_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Rapporto di audit interno\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_03_Appendice_2_\u2013_Rapporto_di_audit_interno_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"},{\"t\":\"Checklist per l'audit interno\",\"doc_link\":\"\",\"url\":\"\\\/wp-content\\\/uploads\\\/pdf-previews\\\/27001\\\/it\\\/(IT_27001)_04_Appendice_3_-_Checklist_per_l_audit_interno_(Anteprima).pdf\",\"downloadable\":\"\",\"active\":\"\"}]], \n                btn_text: \"PURCHASE\", \n                txt1: \"ACQUISTO\",\n                txt2: \"ANTEPRIMA\",\n                txt3: \"X Chiudi\",\n                txt4: \"Download\",\n            };<\/script><div id=\"panel-64247-0-0-1\" class=\"so-panel widget widget_tabs-and-accordion-widget\" data-index=\"1\" ><div id=\"documents\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-tabs-and-accordion-widget so-widget-tabs-and-accordion-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section data-target=\"toolkit-documents\" class=\"tabs-accordion lazy-load-c\" data-loader=\"tinySliderLoader\">\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"a-title-wrapper\">\n                <h2 class=\"universal-h2\">DOCUMENTI DEL KIT<\/h2>\n                <p>Scopri quali documenti sono inclusi nel Kit Documentazione ISO 27001.<\/p>\n            <\/div>\n                        <div id=\"accordion-tabs\" class=\"academy-tabs\">\n                                <div class=\"accordion-tabs__wrap\">\n                    <div id=\"accordion-tabs-arrows\" class=\"controls custom-tab-arrows\">\n                        <span class=\"prev\">\n                                <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#back\"><\/use>\n    <\/svg>\n                            <\/span>\n                        <span class=\"next\">\n                                <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#next\"><\/use>\n    <\/svg>\n                            <\/span>\n                    <\/div>\n                    <div id=\"accordion-tabs-slider\" class=\"accordion-tabs-js tab-wrap\">\n                                                <div class=\"tabs-accordion__tab\" data-rel=\"sistema-di-gestione\" data-key=\"0\">\n                            <p class=\"tablinks active\" onclick=\"openTab(event, 'accordion-tabs', '0', true)\">SISTEMA DI GESTIONE<\/p>\n                        <\/div>\n                                                <div class=\"tabs-accordion__tab\" data-rel=\"gestione-dei-rischi\" data-key=\"1\">\n                            <p class=\"tablinks \" onclick=\"openTab(event, 'accordion-tabs', '1', true)\">GESTIONE DEI RISCHI<\/p>\n                        <\/div>\n                                                <div class=\"tabs-accordion__tab\" data-rel=\"controlli-per-la-sicurezza-delle-informazioni\" data-key=\"2\">\n                            <p class=\"tablinks \" onclick=\"openTab(event, 'accordion-tabs', '2', true)\">CONTROLLI PER LA SICUREZZA DELLE INFORMAZIONI<\/p>\n                        <\/div>\n                                                <div class=\"tabs-accordion__tab\" data-rel=\"continuit-operativa\" data-key=\"3\">\n                            <p class=\"tablinks \" onclick=\"openTab(event, 'accordion-tabs', '3', true)\">CONTINUIT\u00c0 OPERATIVA<\/p>\n                        <\/div>\n                                                <div class=\"tabs-accordion__tab\" data-rel=\"audit-interno\" data-key=\"4\">\n                            <p class=\"tablinks \" onclick=\"openTab(event, 'accordion-tabs', '4', true)\">AUDIT INTERNO<\/p>\n                        <\/div>\n                                            <\/div>\n                <\/div>\n                            <\/div>\n                    <\/div>\n\n        \n        \n                    <div class=\"tabs-accordion__bottom-btn\">\n                <a href=\"https:\/\/platform.advisera.com\/register\/?product=toolkit&amp;language=IT&amp;country=ALL&amp;framework=ISO 27001&amp;currency=USD\" data-button-inner-text=\"Free trial button - middle\" class=\"pricing__button_demo push-campaign-utms\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n                    Prova gratuita\n                <\/a>\n            <\/div>\n            <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-2\" class=\"so-panel widget widget_checklist-with-pdf-widget\" data-index=\"2\" ><div class=\"panel-widget-style panel-widget-style-for-64247-0-0-2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-checklist-with-pdf-widget so-widget-checklist-with-pdf-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"checklist-with-image-section\">\n    <div class=\"l-section\">\n        <h2 class=\"checklist--title\">Scarica l'elenco di tutti i documenti del Kit Documentazione ISO 27001<\/h2>\n        <div class=\"checklist--row\">\n            <div class=\"checklist--list\">\n                <ul>\n<li>Visualizzi tutti i documenti inclusi nel kit documentazione e i riferimenti alla norma ISO 27001<\/li>\n<li>Visualizzi quali documenti sono obbligatori secondo la norma ISO 27001<\/li>\n<li>Visualizzi la sequenza di implementazione suggerita<\/li>\n<\/ul>\n\n            <\/div>\n            <div class=\"checklist--image\">\n                <iframe src=\"\/themencode-pdf-viewer-sc?file=\/wp-content\/uploads\/pdf-previews\/27001\/it\/Elenco_dei_documenti_del_Kit_Documentazione_ISO_27001_2022_IT.pdf&amp;settings=000000010&amp;lang=en-US#page=&amp;zoom=page-width&amp;pagemode=\" frameborder=\"0\" height=\"360\" data-src=\"\/wp-content\/uploads\/pdf-previews\/27001\/it\/Elenco_dei_documenti_del_Kit_Documentazione_ISO_27001_2022_IT.pdf&amp;settings=000000010&amp;lang=en-US#page=&amp;zoom=page-width&amp;pagemode=\"><\/iframe>\n                <div class=\"cta__bottom-btn\">\n                    <a href=\"\/wp-content\/uploads\/pdf-previews\/27001\/it\/Elenco_dei_documenti_del_Kit_Documentazione_ISO_27001_2022_IT.pdf\" class=\"downloadable\" download>SCARICARE L'ELENCO DEI DOCUMENTI<\/a>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-3\" class=\"so-panel widget widget_block-column-widget\" data-index=\"3\" ><div id=\"value\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-block-column-widget so-widget-block-column-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"circle-column__section\">\n    <div class=\"l-section\">\n        <h2>KIT ISO 27001:<\/h2>\n        <h3>\u00c8 ADATTO ALLA TUA ATTIVIT\u00c0?<\/h3>\n\n        <div class=\"a-row\">\n            <div class=\"circle-column__wrap block-column__wrap\">\n                                                <div class=\"circle-column block-column\">\n                                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"50\" height=\"52\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/05\/bank.png\" alt=\"-\">\n                                        \n                    <h3 class=\"block-column__title\">PREPARATI DA SPECIALISTI <\/h3>\n                    <p class=\"block-column__content\">I toolkit di Advisera sono sviluppati da alcuni dei pi\u00f9 esperti auditor, formatori e consulenti per la norma ISO 27001, nonch\u00e9 da esperti di IA.<\/p>\n\n                <\/div>\n                                                                <div class=\"circle-column block-column\">\n                                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"50\" height=\"52\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/05\/file.png\" alt=\"-\">\n                                        \n                    <h3 class=\"block-column__title\">FACILE DA CAPIRE, SEMPLICE DA USARE <\/h3>\n                    <p class=\"block-column__content\">Tutti i documenti sono precompilati al 90%. L\u2019IA ti aiuter\u00e0 a compilare ogni documento con informazioni specifiche sulla tua azienda, cos\u00ec risparmierai tempo e denaro nel processo di implementazione della norma ISO 27001.<\/p>\n\n                <\/div>\n                                                                <div class=\"circle-column block-column\">\n                                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"50\" height=\"52\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2020\/02\/security_management_icon.png\" alt=\"-\">\n                                        \n                    <h3 class=\"block-column__title\">Realizzato per le piccole imprese <\/h3>\n                    <p class=\"block-column__content\">Abbiamo creato il kit per aiutare le piccole imprese a ridurre al minimo tempi e costi di implementazione. Il nostro kit facile da usare ti aiuter\u00e0 a implementare le tue politiche di gestione della sicurezza e a prepararti per la certificazione ISO 27001.<\/p>\n\n                <\/div>\n                                            <\/div>\n                        <div class=\"cricle-column__bottom-text\"><p>Abbiamo compreso le tue esigenze, trovato le risposte alle tue domande e sviluppato il nostro Kit Documentazione ISO 27001 appositamente per la tua azienda. Il nostro kit non richiede la compilazione di ogni documento necessario a una grande multinazionale. Include invece solo i documenti di cui ha bisogno la TUA azienda.<\/p>\n<\/div>\n                    <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-4\" class=\"so-panel widget widget_payment-toolkit-widget\" data-index=\"4\" ><div class=\"panel-widget-style panel-widget-style-for-64247-0-0-4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-payment-toolkit-widget so-widget-payment-toolkit-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"payment-toolkit__section\">\n    <div class=\"l-section\">\n        \n        <div class=\"a-row\">\n                                                <div class=\"pricing__text payment-toolkit__dual-purchase-enabled\">\n                                    <div class=\"pricing__language\">\n                        <div class=\"pricing__language-text\">\n                            <p>LINGUA DEL KIT DOCUMENTAZIONE<\/p>\n                                                        <div class=\"dropdown\">\n                                <button class=\"dropbtn\">Italian     <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#angle-arrow-down\"><\/use>\n    <\/svg>\n    <\/button>\n                                <div class=\"dropdown-content\">\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/\">English<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/de\/\">Deutsch<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/es\/\">Espa\u00f1ol<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/nl\/\">Nederlands<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/fr\/\">Fran\u00e7ais<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/pt-br\/\">Portugu\u00eas<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/ja\/\">\u65e5\u672c\u8a9e<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/hr\/\">Hrvatski<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/bg\/\">\u0411\u044a\u043b\u0433\u0430\u0440\u0441\u043a\u0438<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/pl\/\">Polski<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/sr\/\">\u0441\u0440\u043f\u0441\u043a\u0438<\/a>\n                                                                        <a href=\"https:\/\/advisera.com\/27001academy\/zh-cn\/\">\u7b80\u4f53\u4e2d\u6587<\/a>\n                                                                    <\/div>\n                            <\/div>\n                                                    <\/div>\n                                            <\/div>\n\n                                        <div class=\"dual-purchase-options\">\n                      <div class=\"dual-purchase-option is-selected\" data-option=\"option_1\" data-url=\"https:\/\/securecheckout.advisera.com\/b\/00w3cv5HL8pi2GTcdSgjC1w?locale=it&#038;CURRENCY=USD\">\n                        <div class=\"dual-purchase-radio\"><span class=\"radio-indicator\"><\/span><\/div>\n                        <div class=\"dual-purchase-content\">\n                          <div class=\"dual-purchase-text\">\n                            <strong class=\"dual-purchase-heading\">Accesso a tutti i 45 documenti del toolkit in una sola volta<\/strong>\n                            <span class=\"dual-purchase-description\">Accedi subito al toolkit completo per la piena conformit\u00e0 ISO 27001.<\/span>\n                          <\/div>\n                          <div class=\"dual-purchase-pricing\">\n                            <div class=\"price-wrap\">\n                                                              <span class=\"currency-text caption-2\">US<\/span>\n                                                            <span class=\"dual-purchase-price\">$897<\/span>\n                                                          <\/div>\n                                                          <span class=\"dual-purchase-price-desc\">pagamento unico<\/span>\n                                                      <\/div>\n                        <\/div>\n                      <\/div>\n                      <div class=\"dual-purchase-option\" data-option=\"option_2\" data-url=\"https:\/\/securecheckout.advisera.com\/b\/8x2dR9fildJC2GTem0gjC1v?locale=it&#038;CURRENCY=USD\">\n                        <div class=\"dual-purchase-radio\"><span class=\"radio-indicator\"><\/span><\/div>\n                        <div class=\"dual-purchase-content\">\n                          <div class=\"dual-purchase-text\">\n                            <strong class=\"dual-purchase-heading\">Accesso a 3 documenti al mese<\/strong>\n                            <span class=\"dual-purchase-description\">Scegli solo i documenti di cui hai bisogno. Nessun impegno, disdici in qualsiasi momento.<\/span>\n                          <\/div>\n                          <div class=\"dual-purchase-pricing\">\n                            <div class=\"price-wrap\">\n                                                              <span class=\"currency-text caption-2\">US<\/span>\n                                                            <span class=\"dual-purchase-price\">$100<\/span>\n                                                          <\/div>\n                                                          <span class=\"dual-purchase-price-desc\">al mese<\/span>\n                                                      <\/div>\n                        <\/div>\n                      <\/div>\n                    <\/div>\n                    \n                                        <a href=\"https:\/\/securecheckout.advisera.com\/b\/00w3cv5HL8pi2GTcdSgjC1w?locale=it&#038;CURRENCY=USD\" class=\"pricing__button push-campaign-utms\" rel=\"noopener noreferrer nofollow\" data-button-inner-text=\"Purchase button - middle\" data-is-btn=\"true\">Acquista ora<\/a>\n                    \n                    \n                                        <a href=\"https:\/\/platform.advisera.com\/register\/?product=toolkit&amp;language=IT&amp;country=ALL&amp;framework=ISO 27001&amp;currency=USD\" data-button-inner-text=\"Free trial button - middle\" class=\"pricing__button_demo push-campaign-utms\" target=\"_blank\" rel=\"noopener noreferrer nofollow\">\n                        Prova gratuita\n                    <\/a>\n                                    \n                <div class=\"pricing__countries\">\n                    <div><p>Venduto in <strong>107 PAESI<\/strong><\/p>\n<\/div>\n                    <div class=\"pricing__paycards\">\n                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"155\" height=\"21\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/images\/newsite\/cards4.png\" alt=\"payment cards\">\n                    <\/div>\n                <\/div>\n                <div class=\"pricing__lock\">\n                    <img decoding=\"async\" class=\"lazy-load-c\" width=\"17\" height=\"26\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/images\/newsite\/lock-icon.png \" alt=\"security key image\">\n                    <span>Fatturazione online sicura al 100%<br>AES-256bit SSL safe<\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n<\/div><\/div><\/div><div id=\"panel-64247-0-0-5\" class=\"so-panel widget widget_accordion-widget\" data-index=\"5\" ><div id=\"features\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-accordion-widget so-widget-accordion-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"accordion-section\"> \n    <h2 class=\"accordion-section__title title-container\">COSA RENDE SPECIALE IL KIT ISO 27001<\/h2>\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"accordion-wrap\">\n                                                <div class=\"accordion\" id=\"accordion-0\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"0\" class=\"accordion-title\">\n                            GUIDA PASSO DOPO PASSO PER LA TUA IMPLEMENTAZIONE\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2026\/06\/iso_27001_toolkit_step_by_set_guidance_it.png\" data-acc-content=\"0\" class=\"accordion-text\">\n                        I documenti del kit ISO 27001 sono organizzati per guidarti nel tuo percorso di implementazione della norma. Sono strutturati in cartelle chiaramente numerate, cos\u00ec sai da dove iniziare e, una volta completato ogni documento, dove proseguire.\n                    <\/p>\n                <\/div>\n                                                                <div class=\"accordion\" id=\"accordion-1\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"1\" class=\"accordion-title\">\n                            PROCEDURE GUIDATE CHE ACCELERANO DEL 50% LA REDAZIONE DEI TUOI DOCUMENTI\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2026\/06\/iso_27001_toolkit_ai_wizard_document_writing_it.png\" data-acc-content=\"1\" class=\"accordion-text\">\n                        Prima di scaricare i documenti, puoi usare procedure guidate per inserire automaticamente il nome e il logo della tua azienda in ogni documento. Con l\u2019aiuto della tecnologia IA, queste procedure guidate suggeriscono automaticamente ruoli e responsabilit\u00e0 per specifiche attivit\u00e0 di sicurezza: poich\u00e9 capire chi deve fare cosa richiede di solito la maggior parte del tempo, questo rappresenta un enorme risparmio di tempo.\n                    <\/p>\n                <\/div>\n                                                                <div class=\"accordion\" id=\"accordion-2\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"2\" class=\"accordion-title\">\n                            COMPLETO AL 90% \u2013 GUIDA PER IL RESTANTE 10%\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2026\/06\/testing_backup_copies_it.png\" data-acc-content=\"2\" class=\"accordion-text\">\n                        Abbiamo gi\u00e0 svolto il 90% del lavoro per cui un consulente ti farebbe pagare. Una volta scaricati i documenti, noterai che sono precompilati con tutto ci\u00f2 che \u00e8 richiesto dalla norma, e dovrai semplicemente esaminarli e adattarli alla tua azienda. Per semplificarti il lavoro, i nostri esperti hanno aggiunto segnaposto nei punti in cui devi inserire le informazioni specifiche della tua azienda.\n                    <\/p>\n                <\/div>\n                                                                <div class=\"accordion\" id=\"accordion-3\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"3\" class=\"accordion-title\">\n                            ISTRUZIONI AGGIUNTIVE PER ATTIVIT\u00c0 PI\u00d9 SPECIFICHE\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2021\/03\/ISO_documentation_video_tutorials_IT.gif\" data-acc-content=\"3\" class=\"accordion-text\">\n                        Completare alcune parti di un documento potrebbe essere una sfida se non l\u2019hai mai fatto prima. In questi casi, abbiamo aggiunto commenti con istruzioni dettagliate e, quando necessario, link ad articoli e video tutorial che ti aiuteranno a comprendere e completare queste sezioni.\n                    <\/p>\n                <\/div>\n                                                                <div class=\"accordion\" id=\"accordion-4\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"4\" class=\"accordion-title\">\n                            DOCUMENTI COMPLETAMENTE PERSONALIZZABILI\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2021\/03\/ISO_documentation_fully_customizable_templates_IT.gif\" data-acc-content=\"4\" class=\"accordion-text\">\n                        La maggior parte delle aziende ha uno stile e una struttura specifica per i propri documenti ufficiali. Ci sono informazioni sull\u2019intestazione, il livello di riservatezza, anche il disegno grafico e il carattere da utilizzare. Tutti i nostri documenti sono completamente personalizzabili, in modo da renderli conformi a come devono essere.\n                    <\/p>\n                <\/div>\n                                                                <div class=\"accordion\" id=\"accordion-5\">\n                    <div class=\"accordion-title__wrap\">\n                        <h3 data-acc-btn=\"5\" class=\"accordion-title\">\n                            TUTTA L\u2019ASSISTENZA CHE TI SERVE\n                            <span class=\"accordion-title__icon accordion-title__icon--open\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#plus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <span class=\"accordion-title__icon accordion-title__icon--close\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#minus-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                        <\/h3>\n                    <\/div>\n                    <p data-inner-image=\"\/wp-content\/uploads\/sites\/5\/2021\/03\/ISO_documentation_support.gif\" data-acc-content=\"5\" class=\"accordion-text\">\n                        La certificazione ISO 27001\/ISO 22301 \u00e8 molto pi\u00f9 che semplice documentazione. L\u2019implementazione della norma deve essere adeguata alla tua azienda e dovrai affrontare in modo adeguato i tuoi dipendenti, la tua direzione e i processi esistenti. <br \/><br \/>Per questo motivo i nostri esperti sono disponibili tramite l\u2019assistenza dal vivo online per rispondere a tutte le domande difficili \u2013 possiamo impostare una chiamata tramite Zoom, MS Teams o qualsiasi altro metodo conveniente per te; o possiamo rispondere alle tue domande via email \u2013 qualunque cosa ti sia pi\u00f9 comoda.\n                    <\/p>\n                <\/div>\n                                            <\/div>\n            <div class=\"accordion-image__wrap\">\n                <img decoding=\"async\" width=\"540\" height=\"448\" class=\"accordion-placeholder__screen lazy-load-c\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/slice-display-transparent.png\" alt=\"-\">\n                                <img decoding=\"async\" width=\"500\" height=\"282\" class=\"accordion-inner__img lazy-load-c\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2026\/06\/iso_27001_toolkit_step_by_set_guidance_it.png\" alt=\"-\">\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-6\" class=\"so-panel widget widget_call-to-action-widget\" data-index=\"6\" ><div class=\"panel-widget-style panel-widget-style-for-64247-0-0-6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-call-to-action-widget so-widget-call-to-action-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><div class=\"cta-widget full_width\">\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"cta-title-wrapper\">\n                                <div class=\"cta__bottom-btn\">\n                                        <a href=\"https:\/\/advisera.com\/27001academy\/schedule-meeting\/\" target=\"_blank\" class=\"cta__bottom-btn push-campaign-utms\" data-button-inner-text=\"Schedule presentation button - middle\">\n                        PIANIFICA UNA PRESENTAZIONE GRATUITA\n                    <\/a>\n                                    <\/div>\n                                <span class=\"cta_container_title\">Vuoi vedere che aspetto hanno i documenti?<\/span>\n                <p>Pianifica una presentazione gratuita e il nostro rappresentante ti mostrer\u00e0 qualsiasi documento ti interessi.<\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><div id=\"panel-64247-0-0-7\" class=\"so-panel widget widget_numbered-list-widget\" data-index=\"7\" ><div id=\"support\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-numbered-list-widget so-widget-numbered-list-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section data-target=\"expert-support\" class=\"numbered-and-image-list\">\n    <h2>ASSISTENZA DA PARTE DI UN ESPERTO<\/h2>\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"numbered-list__section\">\n                <h3 class=\"numbered-list__section-title\">Come funziona l'ASSISTENZA DA PARTE DI UN ESPERTO?<\/h3>\n\n                                <div class=\"numbered-list__box\">\n                    <span class=\"numbered-list__box-number\">1<\/span>\n                    <h4>Assistenza dal vivo da parte di un esperto<\/h4>\n                    <p>Il nostro esperto ISO 27001 sar\u00e0 regolarmente in contatto con te \u2013 ti dir\u00e0 da dove iniziare, quali sono i passi successivi e come risolvere eventuali problemi che potresti dover affrontare. Potrete incontrarvi via Zoom, MS Teams, o tramite qualsiasi altro mezzo tu preferisca.<\/p>\n                <\/div>\n                                <div class=\"numbered-list__box\">\n                    <span class=\"numbered-list__box-number\">2<\/span>\n                    <h4>Assistenza via email<\/h4>\n                    <p>Contattaci in qualsiasi momento durante il tuo progetto di implementazione e ricevi risposte alle tue domande entro 24 ore dai nostri esperti.<\/p>\n                <\/div>\n                                <div class=\"numbered-list__box\">\n                    <span class=\"numbered-list__box-number\">3<\/span>\n                    <h4>Revisione di un documento da parte di un esperto<\/h4>\n                    <p>Una volta completati i tuoi documenti, utilizza i nostri esperti per riesaminarli \u2013 ti daranno risposte e ti indicheranno cosa debba essere migliorato.<\/p>\n                <\/div>\n                \n            <\/div>\n\n            <div class=\"image-and-text-list\">\n                <div class=\"image-and-text-list__wrap\">\n                    <h3>Ecco il nostro team di esperti<\/h3>\n                    <p><p>Il nostro team comprende alcuni dei pi\u00f9 esperti auditor, docenti e consulenti per la norma ISO 27001. Inoltre, siamo orgogliosi delle competenze comunicative del nostro team, che \u00e8 ci aiuta a stabilire rapporti personali con i nostri clienti.<\/p>\n<\/p>\n\n                                        <div class=\"image-and-text-list__box\">\n                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"150\" height=\"150\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2020\/09\/dejan-kosutic-340-300x300.jpg\" alt=\"Dejan Kosutic\">\n                        <div class=\"image-and-text-list__content-wrap\">\n                            <h4>Dejan Kosutic<\/h4>\n                            <div class=\"image-and-text-list__text\">\n                                <p>Esperto capo<br \/>\nISO 27001\/ISO 22301<\/p>\n\n                            <\/div>\n                                                        <a href=\"https:\/\/advisera.com\/27001academy\/consultation\/\">\n                                Pianifica la tua consulenza\n                                <span class=\"button-arrow\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#arrow-right-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <\/a>\n                                                    <\/div>\n                    <\/div>\n                                        <div class=\"image-and-text-list__box\">\n                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"150\" height=\"150\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2017\/04\/rhand-rect-300x300.png\" alt=\"Rhand Leal\">\n                        <div class=\"image-and-text-list__content-wrap\">\n                            <h4>Rhand Leal<\/h4>\n                            <div class=\"image-and-text-list__text\">\n                                <p>Esperto di ISO 27001<br \/>\nper il Brasile<\/p>\n\n                            <\/div>\n                                                        <a href=\"https:\/\/advisera.com\/27001academy\/consultation\/\">\n                                Pianifica la tua consulenza\n                                <span class=\"button-arrow\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#arrow-right-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <\/a>\n                                                    <\/div>\n                    <\/div>\n                                        <div class=\"image-and-text-list__box\">\n                        <img decoding=\"async\" class=\"lazy-load-c\" width=\"150\" height=\"150\" src=\"data:image\/gif;base64,R0lGODlhAQABAAAAACH5BAEKAAEALAAAAAABAAEAAAICTAEAOw==\" data-src=\"\/wp-content\/uploads\/sites\/5\/2018\/02\/Antonio-Jose-Segovia-rect-300x300.png\" alt=\"Antonio Jose Segovia\">\n                        <div class=\"image-and-text-list__content-wrap\">\n                            <h4>Antonio Jose Segovia<\/h4>\n                            <div class=\"image-and-text-list__text\">\n                                <p>Esperto di<br \/>\nISO 27001\/ISO 22301<br \/>\nper America Latina<br \/>\ne Spagna<\/p>\n\n                            <\/div>\n                                                        <a href=\"https:\/\/advisera.com\/27001academy\/consultation\/\">\n                                Pianifica la tua consulenza\n                                <span class=\"button-arrow\">    <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#arrow-right-solid\"><\/use>\n    <\/svg>\n    <\/span>\n                            <\/a>\n                                                    <\/div>\n                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-8\" class=\"so-panel widget widget_q-and-a-list-widget\" data-index=\"8\" ><div id=\"faq\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-q-and-a-list-widget so-widget-q-and-a-list-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"qa-list-widget\">\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <h2 class=\"qa-list-widget__title title-container\">DOMANDE FREQUENTI: ACQUISTO DEL KIT ISO 27001<\/h2>\n\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Quando e come ricever\u00f2 il kit?<\/h3>\n                <p>Subito dopo l\u2019elaborazione della transazione, riceverai un\u2019email con un link per accedere al tuo toolkit tramite il modulo Create Documents di Experta, parte della piattaforma Advisera basata sull\u2019IA per la conformit\u00e0. Non potrebbe essere pi\u00f9 rapido o semplice.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Che cos\u2019\u00e8 Experta AI Copilot?<\/h3>\n                <p>Experta AI Copilot \u00e8 la piattaforma basata sull\u2019IA di Advisera che ti aiuta a creare e personalizzare pi\u00f9 rapidamente i documenti del toolkit. Utilizza una libreria di oltre 1.000 documenti di conformit\u00e0 sviluppati da professionisti Advisera esperti e utilizzati in implementazioni reali. Attraverso semplici domande guidate dall\u2019IA, Experta inserisce direttamente nei documenti i dati specifici della tua azienda e ti consente di scaricare i file completati in formato MS Word o Excel.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Questa tecnologia IA \u00e8 affidabile?<\/h3>\n                <p>Tutte le tecnologie IA utilizzate per questo toolkit sono testate approfonditamente. Inoltre, le procedure guidate basate sull\u2019IA suggeriscono solo i contenuti migliori da inserire, ma puoi sempre ignorare il suggerimento e compilare le tue informazioni. La Knowledge Base basata sull\u2019IA di Experta \u00e8 una knowledge base avanzata in stile chatbot, addestrata sulla knowledge base proprietaria di Advisera per fornire risposte accurate. <\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Quali metodi di pagamento accettate?<\/h3>\n                <p>Accettiamo tutte le principali carte di credito e pagamenti PayPal, e possiamo accettare un bonifico bancario dal tuo conto.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Come mantenete al sicuro le mie informazioni di pagamento?<\/h3>\n                <p>Utilizziamo la tecnologia Secure Socket Layer (SSL), la norma del settore. SSL \u00e8 uno dei metodi pi\u00f9 sicuri al mondo per pagare online. Le tue informazioni di pagamento vengono crittografate e inviate immediatamente al processore di pagamento. Non vediamo le tue informazioni di pagamento e non memorizziamo alcun dato.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Quali valute sono accettate?<\/h3>\n                <p>Accettiamo pagamenti in pi\u00f9 di 50 tra le valute pi\u00f9 comuni, inclusi Dollari statunitensi, Euro, Franchi Svizzeri e Sterline Inglesi.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Non sono sicuro se questi documenti siano ci\u00f2 di cui ho bisogno. \u00c8 possibile dargli un'occhiata prima di acquistarli?<\/h3>\n                <p>Certamente! Clicca sul pulsante \"SCARICA LA DIMOSTRAZIONE GRATUITA\", digita il tuo nome e indirizzo email e potrai avere un'anteprima gratuita di ogni documento prima di prendere una decisione sull\u2019acquisto. Vedrai come sono fatti i modelli e quanto siano facili da compilare.<\/p>\n            <\/div>\n                        <div class=\"qa-list-widget__wrap\">\n                <h3>Chi \u00e8 Advisera?<\/h3>\n                <p>Advisera Expert Solutions Ltd \u00e8 una societ\u00e0 specializzata nel fornire supporto online per l\u2019implementazione ISO. Negli ultimi 10 anni ha coperto tutte le principali norme ISO e vende i propri prodotti in oltre 100 paesi in tutto il mondo. <a href=\"\/it\/chi-siamo\/\" target=\"_blank\">Leggi qui ulteriori informazioni<\/a>.<\/p>\n            <\/div>\n            \n            \n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-9\" class=\"so-panel widget widget_call-to-action-widget\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-call-to-action-widget so-widget-call-to-action-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><div class=\"cta-widget boxed\">\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"cta-title-wrapper\">\n                                <div class=\"cta__bottom-btn\">\n                                        <a href=\"https:\/\/advisera.com\/27001academy\/schedule-meeting\/\" target=\"_blank\" class=\"cta__bottom-btn push-campaign-utms\" data-button-inner-text=\"Schedule presentation button - bottom\">\n                        PIANIFICA UNA PRESENTAZIONE GRATUITA\n                    <\/a>\n                                    <\/div>\n                                <span class=\"cta_container_title\">Vuoi vedere che aspetto hanno i documenti?<\/span>\n                <p>Pianifica una presentazione gratuita e il nostro rappresentante ti mostrer\u00e0 qualsiasi documento ti interessi.<\/p>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><\/div><\/div><div id=\"panel-64247-0-0-10\" class=\"so-panel widget widget_image-and-text-slider-widget\" data-index=\"10\" ><div id=\"reviews\" class=\"panel-widget-style panel-widget-style-for-64247-0-0-10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-image-and-text-slider-widget so-widget-image-and-text-slider-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"image-and-text-slider__section lazy-load-c\" data-loader=\"tinySliderLoader\">\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <div class=\"text-slider__title-wrap\">\n                <h2>COSA DICONO DI NOI<br \/>I NOSTRI CLIENTI<\/h2>\n            <\/div>\n            <div class=\"text-slider__wrap\">\n                <div class=\"text-slider text-slider-js\">\n                                        <div class=\"image-and-text-slider\">\n                        <p>Non ho ancora terminato, ma il kit mi ha aiutato a proseguire in modo rapido ed efficiente. Buona impostazione per l\u2019uso e utili i commenti forniti durante l\u2019uso del kit.<\/p>\n                        <div class=\"text-slider__img-wrap\">\n                                                        <div class=\"text-slider__img-content\">\n                                <span class=\"text-slider__img-title\">Apex CyberTek Solutions, LLC<\/span>\n                                <p>Joel Junker<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"image-and-text-slider\">\n                        <p>Ho acquistato il Kit con il vostro corso. Quello che avete fatto \u00e8 una benedizione per noi Auditor Interni di societ\u00e0 private! Il Kit mi consentir\u00e0 di completare in 4 settimane ci\u00f2 che ne avrebbe richieste 12 senza Kit. Grazie!!!<\/p>\n                        <div class=\"text-slider__img-wrap\">\n                                                        <div class=\"text-slider__img-content\">\n                                <span class=\"text-slider__img-title\">Herzog Contracting Corp.<\/span>\n                                <p>Robert Tanner Jr.<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"image-and-text-slider\">\n                        <p>La vostra documentazione \u00e8 stata davvero di grande aiuto. Il nostro audit di stage 2 \u00e8 luned\u00ec e mi avete davvero aiutato a riempire le aree in cui eravamo carenti. I vostri contenuti sono ci\u00f2 che mi ha colpito di pi\u00f9.<\/p>\n                        <div class=\"text-slider__img-wrap\">\n                                                        <div class=\"text-slider__img-content\">\n                                <span class=\"text-slider__img-title\">System Administrator at Alpha Systems<\/span>\n                                <p>Timothy Cohen<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                        <div class=\"image-and-text-slider\">\n                        <p>\u00c8 molto pi\u00f9 semplice strutturare la nostra documentazione ISO 27001 sulla base di una serie di modelli piuttosto che dover partire da zero.<\/p>\n                        <div class=\"text-slider__img-wrap\">\n                                                        <div class=\"text-slider__img-content\">\n                                <span class=\"text-slider__img-title\">Antrotech ApS<\/span>\n                                <p>Claus Nedergaard Jacobsen<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n                <div class=\"controls custom-arrows\">\n                    <span class=\"prev\">\n                            <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#back\"><\/use>\n    <\/svg>\n                        <\/span>\n                    <span class=\"next\">\n                            <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#next\"><\/use>\n    <\/svg>\n                        <\/span>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><\/div><div id=\"panel-64247-0-0-11\" class=\"so-panel widget widget_image-slider-widget\" data-index=\"11\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-image-slider-widget so-widget-image-slider-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section class=\"img-slider__section lazy-load-c\" data-loader='tinySliderLoader'>\n    <div class=\"l-section\">\n        <div class=\"a-row\">\n            <h2 class=\"img-slider__section__title\">I nostri clienti<\/h2>\n            <div class=\"controls customized-arrows\">\n                <span class=\"prev\">\n                        <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#back\"><\/use>\n    <\/svg>\n                    <\/span>\n                <span class=\"next\">\n                        <svg fill=\"currentColor\" class=\"tj-c-icon tj-c-icon--sm tj-c-icon--green\">\n        <use xlink:href=\"https:\/\/advisera.com\/27001academy\/wp-content\/themes\/academy_v2.0\/sprite\/icons.svg#next\"><\/use>\n    <\/svg>\n                    <\/span>\n            <\/div>\n            <div class=\"img-slider img-slider-js\">\n                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/gosecurity-logo.png\" alt=\"-\">\n                <\/div>\n                                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/e-accent-logo.png\" alt=\"-\">\n                <\/div>\n                                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/eisur-logo.png\" alt=\"-\">\n                <\/div>\n                                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/kyocera-logo.png\" alt=\"-\">\n                <\/div>\n                                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/reflex-logo.png\" alt=\"-\">\n                <\/div>\n                                                                <div>\n                    <img decoding=\"async\" class=\"lazy-load-slider lazy-load-c\" width=\"160\" height=\"83\" src=\"data:image\/svg+xml,%3Csvg%20xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039;%20viewBox=&#039;0%200%20211%2076&#039;%3E%3C\/svg%3E\" data-src=\"\/wp-content\/uploads\/sites\/5\/2019\/06\/thirdware-logo.png\" alt=\"-\">\n                <\/div>\n                                            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><div id=\"panel-64247-0-0-12\" class=\"so-panel widget widget_demo-download-modal-widget\" data-index=\"12\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-demo-download-modal-widget so-widget-demo-download-modal-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><section id=\"free-preview-modal\" class=\"modal__overlay overlay\" aria-hidden=\"true\">\n    <div class=\"modal__dialog\">\n        <div class=\"modal__content\">\n            <a class=\"modal__close\" data-modal-id=\"free-preview-modal\">&times;<\/a>\n            <div class=\"modal__header\">\n                <h2 class=\"modal__title\">Download anteprima gratuita<\/h2>\n                <p class=\"hubspot-form-wrap-load\">Ottieni un\u2019anteprima GRATUITA del Kit Documentazione ISO 27001. Una volta scaricata la demo gratuita, il nostro rappresentante ti contatter\u00e0 e ti mostrer\u00e0 tutti i documenti che ti interessano.\n\n<\/p>\n            <\/div>\n            <div class=\"modal__body form-free-preview-download-inner hubspot-form-wrap no-label form-re\">\n                <div class=\"free-preview-download hubspot-form-wrap-load\">\n                    <div class=\"a-row\">\n                        <div class=\"tk-thumb\">\n                            <img decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/5\/2019\/01\/27001-regular-toolkit-box-it.png\" alt=\"-\" width=\"245\" height=\"300\">\n                        <\/div>\n                        <div class=\"toolkit-demo-form form-with-help-text\">\n                            <div id=\"hs-form-fp\"><\/div>\n                                    <!--[if lte IE 8]>\n        <script charset=\"utf-8\" type=\"text\/javascript\" src=\"\/\/js.hsforms.net\/forms\/v2-legacy.js\"><\/script>\n        <![endif]-->\n        <script>\n            (function($) {\n                $(document).ready(function() {\n                    var target = $(\"#hs-form-fp\");\n\n                    function loadHs(cb) {\n                        if (window.hs_loading) return;\n                        if (window.hs_loaded) return cb();\n                        window.hs_loading = true;\n                        $.ajaxSetup({\n                            cache: true\n                        });\n                        $.getScript('\/\/js.hsforms.net\/forms\/v2.js', function() {\n                            window.hs_loaded = true;\n                            window.hs_loading = false;\n                            cb();\n                        });\n                    }\n\n                    function createHsForm() {\n                        loadHs(function() {\n                            if (target.find('form')[0]) return;\n                            hbspt.forms.create({\n                                css: \"\",\n                                portalId: \"1983423\",\n                                formId: \"b113e7e5-30f4-482f-a470-59371ac2df11\",\n                                target: \"#hs-form-fp\",\n                                onFormSubmit: function() {\n                                    setTimeout(function() {\n                                        jQuery(\".hubspot-form-wrap-load\").hide();\n                                        jQuery(\".hubspot-form-wrap-success\").show();\n                                    }, 300);\n                                    window.dataLayer.push({\n                                        event: \"GTMevent\",\n                                        eventCategory: \"overlay\",\n                                        eventAction: \"form-submission\",\n                                        eventLabel: $(\"#free-preview-modal .modal__header .modal__title\").text(),\n                                        page_location: window.location.href,\n                                        page_path: window.location.pathname\n                                    });\n                                }\n                            });\n                        });\n                    }\n\n                    if ($('body').hasClass('page-template-page-toolkit')) {\n                        !target.children().length && target.append('<div class=\"simple-preloader\"><\/div>');\n                        $('.modal__open').on('click', createHsForm);\n                    } else createHsForm()\n                });\n            })(jQuery);\n        <\/script>\n    \n                        <\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"hubspot-form-wrap-success\">\n                    <div class=\"submitted-message\">\n                        Ti sei registrato correttamente: fai clic sul pulsante in basso per scaricare la demo gratuita.\n\n\n                        <a class=\"btn-orange-global\" href=\"\/27001academy\/wp-content\/uploads\/zip_downloads\/27001\/27001_Previews_IT.zip\">\n                            CLICCA QUI PER INIZIARE IL DOWNLOAD                        <\/a>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/section><\/div><\/div><div id=\"panel-64247-0-0-13\" class=\"so-panel widget widget_generic-widget panel-last-child\" data-index=\"13\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-generic-widget so-widget-generic-widget-default-d75171398898-64247\"\n\t\t\t\n\t\t><div id=\"scrollMenuTest\">\n    <div class=\"sections-menu\">\n        <ul class=\"sections-menu-inner\">\n            <li><a class=\"scrollToID\" href=\"#overview\"><span>Panoramica<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#documents\"><span>Documenti<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#value\"><span>Valore<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#features\"><span>Caratteristiche<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#support\"><span>Assistenza<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#faq\"><span>FAQ<\/span><\/a><\/li>\n            <li><a class=\"scrollToID\" href=\"#reviews\"><span>Recensioni<\/span><\/a><\/li>\n        <\/ul>\n    <\/div>\n<\/div>\n\n<script>\n\t(function ($) {\n\t\t$(function () {\n\t\t\tfunction gtag(){dataLayer.push(arguments);}\n\t\t\tfunction gtag_report_conversion(url, id) {\n\t\t\t\tvar callback = function () {\n\t\t\t\tif (typeof(url) != 'undefined') {\n\t\t\t\t\twindow.location = url;\n\t\t\t\t}\n\t\t\t\t};\n\t\t\t\tvar goal_id = id;\n\t\t\t\tgtag('event', 'conversion', {\n\t\t\t\t\t'send_to': 'AW-991742250\/'+ goal_id,\n\t\t\t\t\t'value': 1.0,\n\t\t\t\t\t'currency': 'USD',\n\t\t\t\t\t'event_callback': callback\n\t\t\t\t});\n\t\t\t\treturn false;\n\t\t\t}\n\t\t\tfunction uet_report_conversion_free_trial(el_label, el_cat) {\n\t\t\t\twindow.uetq = window.uetq || [];\n\t\t\t\twindow.uetq.push ('event', 'iso27001_toolkit_free_trial', {'event_category': el_cat, 'event_label': el_label});\n\t\t\t}\n\t\t\t$('.pricing__button_demo[data-eventcategory=\"free_trial_button_hero_click\"], .pricing__button_demo[data-eventcategory=\"free_trial_button_documents_click\"], .pricing__button_demo[data-eventcategory=\"free_trial_button_payment_widget_click\"]').click(function () {\n\t\t\t\tvar el_label = $(this).text();\n\t\t\t\tvar el_cat = $(this).attr(\"data-eventcategory\");\n\t\t\t\tuet_report_conversion_free_trial(el_label, el_cat);\n\t\t\t\tgtag_report_conversion(undefined, 'T-vDCN7j0v8ZEKqS89gD');\n\t\t\t\twindow.lintrk('track', { conversion_id: 19254996 });\n\t\t\t});\n\t\t\tfunction uet_report_conversion_purchase(el_label, el_cat) {\n\t\t\t\twindow.uetq = window.uetq || [];\n\t\t\t\twindow.uetq.push('event', 'iso27001_toolkit_purchase', {'event_category': el_cat, 'event_label': el_label});\n\t\t\t}\n\t\t\t$('.pricing__button[data-eventcategory=\"purchase_button_hero_click\"], .pricing__button[data-eventcategory=\"purchase_button_payment_widget_click\"], .table-price-box__btn[data-eventcategory=\"purchase_button_pricing_click\"]').click(function () {\n\t\t\t\tvar el_label = $(this).text();\n\t\t\t\tvar el_cat = $(this).attr(\"data-eventcategory\");\n\t\t\t\tuet_report_conversion_purchase(el_label, el_cat);\n\t\t\t\tgtag_report_conversion(undefined, 'mfOWCNO53P8ZEKqS89gD');\n\t\t\t\twindow.lintrk('track', { conversion_id: 19260908 });\n\t\t\t});\n\t\t});\n\t})(jQuery);\n<\/script><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>KIT DOCUMENTAZIONE ISO 27001 &#8211; IMPLEMENTAZIONE BASATA SULL\u2019IA Raggiungi pi\u00f9 rapidamente la conformit\u00e0 alla ISO 27001 con documenti strutturati, guida esperta e personalizzazione basata sull\u2019IA. Guida passo dopo passo con ASSISTENZA DAL VIVO DI UN ESPERTO 45 modelli di documenti adattati all\u2019ultima revisione 2022 della norma \u2013 accesso illimitato a tutti i documenti richiesti per &#8230;<\/p>\n","protected":false},"author":161,"featured_media":82631,"parent":0,"menu_order":105,"comment_status":"closed","ping_status":"closed","template":"page-toolkit.php","meta":{"_acf_changed":false,"footnotes":""},"toolkit-document-types":[312],"class_list":["post-64247","page","type-page","status-publish","has-post-thumbnail","hentry","toolkit-document-types-iso-27001-documentation-toolkit"],"acf":[],"_links":{"self":[{"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/pages\/64247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/users\/161"}],"replies":[{"embeddable":true,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/comments?post=64247"}],"version-history":[{"count":3,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/pages\/64247\/revisions"}],"predecessor-version":[{"id":105757,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/pages\/64247\/revisions\/105757"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/media\/82631"}],"wp:attachment":[{"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/media?parent=64247"}],"wp:term":[{"taxonomy":"toolkit-document-types","embeddable":true,"href":"https:\/\/advisera.com\/27001academy\/it\/wp-json\/wp\/v2\/toolkit-document-types?post=64247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}