{"id":87832,"date":"2022-11-03T07:20:08","date_gmt":"2022-11-03T07:20:08","guid":{"rendered":"https:\/\/advisera.com\/toolkit-documents\/registro-delle-valutazioni-dimpatto-sulla-protezione-dei-dati\/"},"modified":"2023-11-07T15:47:32","modified_gmt":"2023-11-07T15:47:32","slug":"registro-delle-valutazioni-dimpatto-sulla-protezione-dei-dati","status":"publish","type":"adv_documents","link":"https:\/\/advisera.com\/it\/kit-documenti\/gdpr-della-ue\/registro-delle-valutazioni-dimpatto-sulla-protezione-dei-dati\/","title":{"rendered":"Registro delle Valutazioni d&#8217;Impatto sulla Protezione dei Dati"},"content":{"rendered":"<div id=\"pl-87832\"  class=\"panel-layout\" ><div id=\"pg-87832-0\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-hero siteorigin-panels-stretch bottom-padding-normal hero-section panel-row-style panel-row-style-for-87832-0\" data-stretch-type=\"full\" ><div id=\"pgc-87832-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-0-0-0\" class=\"so-panel widget widget_adv_content_editor panel-first-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_content_editor so-widget-adv_content_editor-base\"\n\t\t\t\n\t\t>\n<section class=\"adv-content-editor \">\n         <span class=\"h6 above-heading\">Modello di documento GDPR dell'UE:<\/span>\n   \n         <h1 class=\"h1-m main-title\">Registro delle Valutazioni d\u2019Impatto sulla Protezione dei Dati<\/h1>\n   \n   \n\n   \n         <div class=\"adv-content\">\n         <p>Un documento utilizzato dalle aziende per documentare la Valutazione d\u2019Impatto sulla Protezione dei Dati \u2013 questo comprende il questionario Soglia che analizza quali attivit\u00e0 di trattamento dei dati debbano essere analizzate e il questionario DPIA che valuta i rischi e definisce le misure di sicurezza \/ difesa.<\/p>\n<p>Il documento \u00e8 ottimizzato per le piccole e medie imprese \u2013 crediamo che documenti eccessivamente complessi e lunghi rappresentino uno sforzo superfluo per te.<\/p>\n      <\/div>\n   <\/section><\/div><\/div><div id=\"panel-87832-0-0-1\" class=\"so-panel widget widget_adv-related-document-list panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv-related-document-list so-widget-adv-related-document-list-base\"\n\t\t\t\n\t\t><section class=\"adv-related-document-list \">\n         <h2 class=\"h5 uppercase related-documents\">DOCUMENTI COLLEGATI<\/h2>\n       <ol class=\"caret\">\n                           <li><a href=\"https:\/\/advisera.com\/it\/kit-documenti\/gdpr-della-ue\/metodologia-di-valutazione-dimpatto-sulla-protezione-dei-dati\/\">Metodologia di Valutazione d&#8217;Impatto sulla Protezione dei Dati<\/a><\/li>\n                           <li><a href=\"https:\/\/advisera.com\/it\/kit-documenti\/gdpr-della-ue\/elenco-delle-attivita-di-trattamento-dei-dati\/\">Elenco delle Attivit\u00e0 di Trattamento dei Dati<\/a><\/li>\n                           <li><a href=\"https:\/\/advisera.com\/it\/kit-documenti\/gdpr-della-ue\/linee-guida-per-lelenco-dei-dati-e-la-mappatura-delle-attivita-di-trattamento\/\">Linee guida per l\u2019Elenco dei Dati e la Mappatura delle Attivit\u00e0 di Trattamento<\/a><\/li>\n            <\/ol>\n<\/section><\/div><\/div><\/div><div id=\"pgc-87832-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-0-1-0\" class=\"so-panel widget widget_adv_toolkit_purchase panel-first-child panel-last-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_toolkit_purchase so-widget-adv_toolkit_purchase-base\"\n\t\t\t\n\t\t><section class=\"single-lang toolkit-purchase\">\r\n\t<div class=\"adv-form\">\r\n\r\n\t\t\t<div class=\"form-field hs-fieldtype-select hs-input focused\">\r\n            <legend class=\"hs-field-desc\">Seleziona la lingua del prodotto<\/legend>\r\n            <select name=\"country\" id=\"toolkit-language-links\" class=\"countryField\">\r\n\t\t\t\t<option value=\"https:\/\/advisera.com\/\">English<\/option><option value=\"https:\/\/advisera.com\/mt\/\">English (Malta)<\/option><option value=\"https:\/\/advisera.com\/da\/\">Dansk<\/option><option value=\"https:\/\/advisera.com\/de\/\">Deutsch<\/option><option value=\"https:\/\/advisera.com\/at\/\">Deutsch (\u00d6sterreich)<\/option><option value=\"https:\/\/advisera.com\/el\/\">\u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ac (\u0395\u03bb\u03bb\u03ac\u03b4\u03b1)<\/option><option value=\"https:\/\/advisera.com\/el-cy\/\">\u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ac (\u039a\u03cd\u03c0\u03c1\u03bf\u03c2)<\/option><option value=\"https:\/\/advisera.com\/es\/\">Espa\u00f1ol<\/option><option value=\"https:\/\/advisera.com\/fr\/\">Fran\u00e7ais<\/option><option value=\"https:\/\/advisera.com\/fr-be\/\">Fran\u00e7ais (Belgique)<\/option><option value=\"https:\/\/advisera.com\/hr\/\">Hrvatski<\/option><option value=\"https:\/\/advisera.com\/it\/\"selected=\"selected\">Italiano<\/option><option value=\"https:\/\/advisera.com\/lv\/\">Latvie\u0161u<\/option><option value=\"https:\/\/advisera.com\/lt\/\">Lietuvi\u0173<\/option><option value=\"https:\/\/advisera.com\/hu\/\">Magyar<\/option><option value=\"https:\/\/advisera.com\/nl\/\">Nederlands<\/option><option value=\"https:\/\/advisera.com\/nl-be\/\">Nederlands (Belgi\u00eb)<\/option><option value=\"https:\/\/advisera.com\/pt-pt\/\">Portugu\u00eas (Portugal)<\/option><option value=\"https:\/\/advisera.com\/pt-br\/\">Portugu\u00eas (Brasil)<\/option><option value=\"https:\/\/advisera.com\/ro\/\">Rom\u00e2n\u0103<\/option><option value=\"https:\/\/advisera.com\/sl\/\">Sloven\u0161\u010dina<\/option><option value=\"https:\/\/advisera.com\/fi\/\">Suomi<\/option><option value=\"https:\/\/advisera.com\/sv\/\">Svenska<\/option>           <\/select>\r\n        <\/div>\r\n                    <div class=\"adv-price\">\r\n\r\n\t    \t\t\r\n\t\t\t\t\t<div class=\"price-wrap\">\r\n\t\t\t\r\n\t\t\t\t<span class=\"h2 h1-m\">89.90<\/span>\r\n\r\n\t\t\t\t\t\t\t<span class=\"currency-text caption-2 after-price\">EUR<\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t        <\/div>\r\n        \t<\/div>\r\n\t\t<div class=\"adv-buttons\">\r\n\t\t\t\t\t<div class=\"adv-toolkit-button\">\r\n\t\t\t\t<a href=\"https:\/\/shop.advisera.com\/order\/checkout.php?PRODS=19878516&amp;QTY=1&amp;CART=1&amp;CARD=1&amp;LANG=it&amp;SHORT_FORM=1&amp;CURRENCY=USD\" class=\"pricing__button btn btn-cta push-campaign-utms \" rel=\"noopener noreferrer nofollow\" data-button-inner-text=\"Purchase button - top\">Procedi con il pagamento<\/a>\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\r\n\t<\/div>\r\n\r\n\t<div class=\"adv-video \">\r\n\r\n\t\t\t\t<div class=\"wrapper relative has_frame\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"absolute\" src=\"https:\/\/advisera.com\/wp-content\/themes\/advisera\/assets\/images\/certification-toolkit-document-frame.svg\" alt=\"certification-toolkit-document-frame\" title=\"\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"pdf-image video-image absolute\" data-lity href=\"#document-preview\">\r\n\t\t\t\t\t<div class=\"toolkit-media-wrap\">\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/pdf-previews\/eugdpr\/it\/thumbnails\/05.2_Registro_delle_Valutazioni_d_Impatto_sulla_Protezione_dei_Dati_Preview_IT.png\" alt=\"-\" title=\"\">\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<div class=\"play-icon\">\n\t<div class=\"wrapper\">\n<!-- \t\t<svg width=\"75\" height=\"75\" viewBox=\"0 0 512 512\">\n\t\t  <path d=\"m289.8,200.2h-49.3v-49.3c0-11.3-9.1-20.4-20.4-20.4-11.3,0-20.4,9.1-20.4,20.4v49.3h-49.3c-11.3,0-20.4,9.1-20.4,20.4 0,11.3 9.1,20.4 20.4,20.4h49.3v49.3c0,11.3 9.1,20.4 20.4,20.4 11.3,0 20.4-9.1 20.4-20.4v-49.3h49.3c11.3,0 20.4-9.1 20.4-20.4 0-11.3-9.2-20.4-20.4-20.4z\"><\/path>\n\t\t  <path d=\"m220.2,388.7c-92.9,0-168.2-75.2-168.2-168.1s75.3-168.1 168.2-168.1 168.1,75.3 168.1,168.1-75.3,168.1-168.1,168.1zm274.8,78l-113.3-113.3c29.7-36.1 47.6-82.4 47.6-132.8 0-115.5-93.6-209.2-209.2-209.2s-209.1,93.7-209.1,209.2 93.6,209.2 209.2,209.2c50.4,0 96.6-17.8 132.7-47.5l113.3,113.3c5.2,5.3 21.1,7.9 28.9,0 7.9-8 7.9-20.9-0.1-28.9z\" fill=\"#19191A\" fill-opacity=\"0.7\"><\/path>\n\t\t<\/svg> -->\n\t\t<svg width=\"75\" height=\"75\" viewBox=\"0 0 512 512\">\n\t\t  <path d=\"m289.8,200.2h-49.3v-49.3c0-11.3-9.1-20.4-20.4-20.4-11.3,0-20.4,9.1-20.4,20.4v49.3h-49.3c-11.3,0-20.4,9.1-20.4,20.4 0,11.3 9.1,20.4 20.4,20.4h49.3v49.3c0,11.3 9.1,20.4 20.4,20.4 11.3,0 20.4-9.1 20.4-20.4v-49.3h49.3c11.3,0 20.4-9.1 20.4-20.4 0-11.3-9.2-20.4-20.4-20.4z\" fill=\"#fff\" fill-opacity=\"1\"><\/path>\n\t\t  <path d=\"m220.2,388.7c-92.9,0-168.2-75.2-168.2-168.1s75.3-168.1 168.2-168.1 168.1,75.3 168.1,168.1-75.3,168.1-168.1,168.1zm274.8,78l-113.3-113.3c29.7-36.1 47.6-82.4 47.6-132.8 0-115.5-93.6-209.2-209.2-209.2s-209.1,93.7-209.1,209.2 93.6,209.2 209.2,209.2c50.4,0 96.6-17.8 132.7-47.5l113.3,113.3c5.2,5.3 21.1,7.9 28.9,0 7.9-8 7.9-20.9-0.1-28.9z\" fill=\"#fff\" fill-opacity=\"1\"><\/path>\n\t\t<\/svg>\t\t\n\t<\/div>\n<\/div>\n\t\t\t\t<\/a>\r\n\t\t\t\t<div id=\"document-preview\" class=\"lity-hide\" style=\"width:90vw; height: 90vh\">\r\n\t\t\t\t\t<iframe loading=\"lazy\" class=\"pvfw-pdf-viewer-frame\" data-args=\"advisera-pdf\" style=\"width: 100%; height: 100%; overflow: scroll;\" src=\"\" data-openfile=\"\/themencode-pdf-viewer-sc?file=\/wp-content\/uploads\/pdf-previews\/eugdpr\/it\/05.2_Registro_delle_Valutazioni_d_Impatto_sulla_Protezione_dei_Dati_Preview_IT.pdf&settings=001000010&lang=en-US#page=&zoom=page-width\" width=\"100%\" height=\"100%\" scrolling=\"yes\">Iframes not supported<\/iframe>\r\n\t\t\t\t<\/div>\r\n\t\t\t\r\n\r\n\t\t\r\n\t<\/div>\r\n<\/section><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-1\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-features siteorigin-panels-stretch top-padding-s bottom-padding-s panel-row-style panel-row-style-for-87832-1\" data-stretch-type=\"full\" ><div id=\"pgc-87832-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-1-0-0\" class=\"so-panel widget widget_adv_cards panel-first-child panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_cards so-widget-adv_cards-base\"\n\t\t\t\n\t\t>\n<section class=\"cards-with-icons style-icons-top  heading-style-h2\">\n        <div class=\"card-header\">\n        <div class=\"title\">\n                    <h2 class=\"cards-main-title\">\n            \tCaratteristiche del documento            <\/h2>\n                        \n        <\/div>\n    <\/div>  \n          \n    <div class=\"cards-wrapper has-2-columns text-dark \">\n \n        \n            \n                  \t\n            <div class=\"card bg-white\">  \n                       \n                <div class=\"card-left figure\">\n                    <img decoding=\"async\" width=\"184\" height=\"184\" src=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/single-document-overview.svg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"-\" title=\"\">                <\/div>\n                <div class=\"card-right\">\n                                                           <h3 class=\"card-title h4 h3-m\">\n                                                                                Panoramica                            \n                                                        \n                                                \n                    <\/h3>                                  \n                                                          <div class=\"c-subtitle \">\n                    \t<ul>\n<li><strong>Prezzo<\/strong><br \/>\n89.90 EUR<\/li>\n<li><strong>Conforme alla<\/strong><br \/>\nGDPR Articolo 35<\/li>\n<li><strong>Formato<\/strong><br \/>\nMS Excel 2013, MS Excel 2016, MS Excel 2019<\/li>\n<li><strong>Numero di pagine<\/strong><br \/>\n1 sheet<\/li>\n<li><strong>Lingua in cui \u00e8 scritto il documento<\/strong><br \/>\nItaliano. Per altre lingue, cliccare qui: <a href=\"https:\/\/advisera.com\/\">English<\/a>, <a href=\"https:\/\/advisera.com\/mt\/\">English (Malta)<\/a>, <a href=\"https:\/\/advisera.com\/da\/\">Dansk<\/a>, <a href=\"https:\/\/advisera.com\/de\/\">Deutsch<\/a>, <a href=\"https:\/\/advisera.com\/at\/\">Deutsch (\u00d6sterreich)<\/a>, <a href=\"https:\/\/advisera.com\/el\/\">\u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ac (\u0395\u03bb\u03bb\u03ac\u03b4\u03b1)<\/a>, <a href=\"https:\/\/advisera.com\/el-cy\/\">\u0395\u03bb\u03bb\u03b7\u03bd\u03b9\u03ba\u03ac (\u039a\u03cd\u03c0\u03c1\u03bf\u03c2)<\/a>, <a href=\"https:\/\/advisera.com\/es\/\">Espa\u00f1ol<\/a>, <a href=\"https:\/\/advisera.com\/fr\/\">Fran\u00e7ais<\/a>, <a href=\"https:\/\/advisera.com\/fr-be\/\">Fran\u00e7ais (Belgique)<\/a>, <a href=\"https:\/\/advisera.com\/hr\/\">Hrvatski<\/a>, <a href=\"https:\/\/advisera.com\/it\/\">Italiano<\/a>, <a href=\"https:\/\/advisera.com\/lv\/\">Latvie\u0161u<\/a>, <a href=\"https:\/\/advisera.com\/lt\/\">Lietuvi\u0173<\/a>, <a href=\"https:\/\/advisera.com\/hu\/\">Magyar<\/a>, <a href=\"https:\/\/advisera.com\/nl\/\">Nederlands<\/a>, <a href=\"https:\/\/advisera.com\/nl-be\/\">Nederlands (Belgi\u00eb)<\/a>, <a href=\"https:\/\/advisera.com\/pt-pt\/\">Portugu\u00eas (Portugal)<\/a>, <a href=\"https:\/\/advisera.com\/pt-br\/\">Portugu\u00eas (Brasil)<\/a>, <a href=\"https:\/\/advisera.com\/ro\/\">Rom\u00e2n\u0103<\/a>, <a href=\"https:\/\/advisera.com\/sl\/\">Sloven\u0161\u010dina<\/a>, <a href=\"https:\/\/advisera.com\/fi\/\">Suomi<\/a>, <a href=\"https:\/\/advisera.com\/sv\/\">Svenska<\/a>.<\/li>\n<\/ul>\n<\/div>\n                     \n                <\/div> \n               \n            \n                       \n            <\/div>\n           \n        \n            \n                  \t\n            <div class=\"card bg-white\">  \n                       \n                <div class=\"card-left figure\">\n                    <img decoding=\"async\" width=\"184\" height=\"184\" src=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/single-document-usability.svg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"-\" title=\"\">                <\/div>\n                <div class=\"card-right\">\n                                                           <h3 class=\"card-title h4 h3-m\">\n                                                                                Usabilit\u00e0                            \n                                                        \n                                                \n                    <\/h3>                                  \n                                                          <div class=\"c-subtitle \">\n                    \t<ul>\n<li><strong>Posso modificare il documento?<\/strong><br \/>\nS\u00ec. Il documento \u00e8 completamente modificabile \u2013 inserisci solo le informazioni specifiche per la tua azienda.<\/li>\n<li><strong>\u00c8 accettato dalle autorit\u00e0 di vigilanza?<\/strong><br \/>\nS\u00ec, il documento \u00e8 scritto da consulenti con una vasta esperienza nel trattare con le autorit\u00e0 competenti per la protezione dei dati.<\/li>\n<li><strong>Istruzioni ben definite<\/strong><br \/>\nI modelli di documenti contengono una media di venti commenti ciascuno e offrono chiare indicazioni per la loro compilazione.<\/li>\n<li><strong>Progettato pensando alla tua azienda<\/strong><br \/>\nIl modello \u00e8 stato creato per le piccole e medie imprese.<\/li>\n<\/ul>\n<\/div>\n                     \n                <\/div> \n               \n            \n                       \n            <\/div>\n           \n        \n    <\/div>\n    <\/section><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-2\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-available-in-toolkits top-padding-s bottom-padding-s panel-row-style panel-row-style-for-87832-2\" ><div id=\"pgc-87832-2-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-2-0-0\" class=\"so-panel widget widget_adv_related_toolkit_slider panel-first-child panel-last-child\" data-index=\"4\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_related_toolkit_slider so-widget-adv_related_toolkit_slider-base\"\n\t\t\t\n\t\t>\n<section class=\"related-toolkits toolkit-grid\" data-items=\"3\" data-autoplay=\"true\">\n         <h2>Disponibile anche in questi Kit<\/h2>\n      <div class=\"has-3-columns\">\n               <div class=\"card\">\n            <div class=\"flex-wrap\">\n               <div class=\"card-img-wrap\">\n                  <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-del-gdpr-della-ue\/\" class=\"carousel-image\">\n                     <img decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/Kit-Documentazione-del-GDPR-dellUE.jpg\" class=\"featured-toolkit-image wp-post-image\" alt=\"-\" srcset=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/Kit-Documentazione-del-GDPR-dellUE.jpg 900w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/Kit-Documentazione-del-GDPR-dellUE-300x169.jpg 300w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/10\/Kit-Documentazione-del-GDPR-dellUE-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">                  <\/a>\n               <\/div>\n               <div class=\"card-content\">\n                   <h3 class=\"h4 card-title\"><a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-del-gdpr-della-ue\/\" class=\"card-title\">\n                     Kit Documentazione del GDPR dell\u2019UE                  <\/a><\/h3>   \n                  <div class=\"excerpt\">\n                     Kit Documentazione del GDPR dell\u2019UE Completamente ottimizzato per piccole e medie imprese Ottieni da solo la conformit\u00e0 al GDPR dell'UE [&hellip;]                  <\/div>          \n               <\/div>\n               <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-del-gdpr-della-ue\/\" class=\"btn btn-empty\">\n                  Vai al Kit Documentazione<i class=\"icon icon-arrow\"><\/i>\n               <\/a>\n            <\/div>\n         <\/div>\n               <div class=\"card\">\n            <div class=\"flex-wrap\">\n               <div class=\"card-img-wrap\">\n                  <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-premium-del-gdpr-dellue\/\" class=\"carousel-image\">\n                     <img decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-Documentazione-Premium-del-GDPR-dellUE.jpg\" class=\"featured-toolkit-image wp-post-image\" alt=\"Kit Documentazione Premium del GDPR dell\u2019UE\" srcset=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-Documentazione-Premium-del-GDPR-dellUE.jpg 900w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-Documentazione-Premium-del-GDPR-dellUE-300x169.jpg 300w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-Documentazione-Premium-del-GDPR-dellUE-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">                  <\/a>\n               <\/div>\n               <div class=\"card-content\">\n                   <h3 class=\"h4 card-title\"><a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-premium-del-gdpr-dellue\/\" class=\"card-title\">\n                     Kit Documentazione Premium del GDPR dell\u2019UE                  <\/a><\/h3>   \n                  <div class=\"excerpt\">\n                     Kit Documentazione Premium del GDPR dell\u2019UE Completamente ottimizzato per piccole e medie imprese Ottieni da solo la conformit\u00e0 al GDPR [&hellip;]                  <\/div>          \n               <\/div>\n               <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-documentazione-premium-del-gdpr-dellue\/\" class=\"btn btn-empty\">\n                  Vai al Kit Documentazione<i class=\"icon icon-arrow\"><\/i>\n               <\/a>\n            <\/div>\n         <\/div>\n               <div class=\"card\">\n            <div class=\"flex-wrap\">\n               <div class=\"card-img-wrap\">\n                  <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-per-la-mappatura-dei-dati-dpia-nel-gdpr-dell-ue\/\" class=\"carousel-image\">\n                     <img decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-per-la-Mappatura-dei-dati-e-la-DPIA-nel-GDPR.jpg\" class=\"featured-toolkit-image wp-post-image\" alt=\"Kit per la Mappatura dei dati e la DPIA nel GDPR dell&#039;UE\" srcset=\"https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-per-la-Mappatura-dei-dati-e-la-DPIA-nel-GDPR.jpg 900w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-per-la-Mappatura-dei-dati-e-la-DPIA-nel-GDPR-300x169.jpg 300w, https:\/\/advisera.com\/wp-content\/uploads\/2022\/11\/Kit-per-la-Mappatura-dei-dati-e-la-DPIA-nel-GDPR-768x432.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" title=\"\">                  <\/a>\n               <\/div>\n               <div class=\"card-content\">\n                   <h3 class=\"h4 card-title\"><a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-per-la-mappatura-dei-dati-dpia-nel-gdpr-dell-ue\/\" class=\"card-title\">\n                     Kit per la Mappatura dei dati e la DPIA nel GDPR dell&#8217;UE                  <\/a><\/h3>   \n                  <div class=\"excerpt\">\n                     Kit per la Mappatura dei dati e la DPIA nel GDPR Completamente ottimizzato per piccole e medie imprese Rendi il [&hellip;]                  <\/div>          \n               <\/div>\n               <a href=\"https:\/\/advisera.com\/it\/kit-documentazione\/kit-per-la-mappatura-dei-dati-dpia-nel-gdpr-dell-ue\/\" class=\"btn btn-empty\">\n                  Vai al Kit Documentazione<i class=\"icon icon-arrow\"><\/i>\n               <\/a>\n            <\/div>\n         <\/div>\n         <\/div>\n<\/section><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-3\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-preview-document siteorigin-panels-stretch top-padding-normal bottom-padding-xs hero-section panel-row-style panel-row-style-for-87832-3\" data-stretch-type=\"full\" ><div id=\"pgc-87832-3-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-3-0-0\" class=\"so-panel widget widget_adv_content_editor panel-first-child\" data-index=\"5\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_content_editor so-widget-adv_content_editor-base\"\n\t\t\t\n\t\t>\n<section class=\"adv-content-editor \">\n   \n         <h2 class=\"h1-m main-title\">Anteprima Documento<\/h2>\n   \n   \n\n   \n         <div class=\"adv-content\">\n         <ol class=\"checklist large-space\">\n<li>Il documento \u00e8 <strong>completamente modificabile<\/strong> in modo che tu lo possa adattare allo stile della tua azienda.<\/li>\n<li>I documenti includono delle <strong>note con indicazioni<\/strong> per tutte le informazioni che \u00e8 necessario inserire.<\/li>\n<li>Ogni documento riporta <strong>commenti e informazioni<\/strong>, che ti guidano durante la compilazione.<\/li>\n<\/ol>\n      <\/div>\n   <\/section><\/div><\/div><div id=\"panel-87832-3-0-1\" class=\"so-panel widget widget_adv_display_site_element panel-last-child\" data-index=\"6\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_display_site_element so-widget-adv_display_site_element-base\"\n\t\t\t\n\t\t><div class=\"site_element-wrap\"><div id=\"pl-86832\"  class=\"panel-layout\" ><div id=\"pg-86832-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch hero-section panel-row-style panel-row-style-for-86832-0\" data-stretch-type=\"full\" ><div id=\"pgc-86832-0-0\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-86832-0-0-0\" class=\"so-panel widget widget_adv_buttons panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_buttons so-widget-adv_buttons-base\"\n\t\t\t\n\t\t>\t<a class=\"btn push-campaign-utms btn-cta\" href=\"https:\/\/advisera.com\/schedule-meeting\/\" target=\"_blank\" aria-label=\"Pianifica una Presentazione Gratuita\">\r\n\t\tPianifica una Presentazione Gratuita\t<\/a>\r\n\r\n<\/div><\/div><\/div><div id=\"pgc-86832-0-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pgc-87832-3-1\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-3-1-0\" class=\"so-panel widget widget_adv-single-document-preview panel-first-child panel-last-child\" data-index=\"7\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv-single-document-preview so-widget-adv-single-document-preview-base\"\n\t\t\t\n\t\t><section class=\"adv-single-document-preview empty-file\">\n    \n        <div class=\"preview-window default-style\" >   \n            <div class=\"adv-classic-loader\"><div class=\"lds-ring\"><div><\/div><div><\/div><div><\/div><div><\/div><\/div><\/div>         \n            <iframe loading=\"lazy\" class=\"pvfw-pdf-viewer-frame\" data-openfile=\"\/themencode-pdf-viewer-sc?file=\/wp-content\/uploads\/pdf-previews\/eugdpr\/it\/05.2_Registro_delle_Valutazioni_d_Impatto_sulla_Protezione_dei_Dati_Preview_IT.pdf&#038;lang=en-US#page=&#038;zoom=page-width\" data-args=\"advisera-pdf\" style=\"width: 100%; height: 100%; overflow: scroll;\" src=\"\" width=\"100%\" height=\"100%\" scrolling=\"yes\">Iframes not supported<\/iframe>\n                        <\/div>\n\n    \n<\/section><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-4\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-reviews siteorigin-panels-stretch panel-row-style panel-row-style-for-87832-4\" data-stretch-type=\"full\" ><div id=\"pgc-87832-4-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-4-0-0\" class=\"so-panel widget widget_adv_display_site_element panel-first-child panel-last-child\" data-index=\"8\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_display_site_element so-widget-adv_display_site_element-base\"\n\t\t\t\n\t\t><div class=\"site_element-wrap\"><div id=\"pl-86827\"  class=\"panel-layout\" ><div id=\"pg-86827-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch top-padding-normal bottom-padding-s panel-row-style panel-row-style-for-86827-0\" data-stretch-type=\"full\" ><div id=\"pgc-86827-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-86827-0-0-0\" class=\"so-panel widget widget_adv_cards_carousel panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_cards_carousel so-widget-adv_cards_carousel-base\"\n\t\t\t\n\t\t>\n<div class=\"cards-carousel text-light style-inside-grid\" data-items=\"3\" data-autoplay=\"true\" data-slideby=\"1\">\n\t      <h2 class=\"carousel-title\">\n      \tMigliaia di Clienti che hanno avuto Successo      <\/h2>\n\t\t<div class=\"carousel-wrap\">\n\t\t\n         <div class=\"card\">               \n               \n            \n            <div class=\"card-content\">\n               <h3 class=\"card-title h5\">\n\t\t            \t\t              \tChristy Bentivoglio\t\t                           <\/h3>\n\t\t\t\t\t\t\t                  <p class=\"description\">\n\t                    \tIl kit mi ha fornito degli ottimi punti di partenza, cos\u00ec non devo creare i vari documenti da zero o perdere tempo a cercare esempi e modelli sul Web.\t                  <\/p>\n                               \n            <\/div>\n                      \n         <\/div>\n      \n         <div class=\"card\">               \n               \n            \n            <div class=\"card-content\">\n               <h3 class=\"card-title h5\">\n\t\t            \t\t              \tVaclav Jakoubek\t\t                           <\/h3>\n\t\t\t\t\t\t\t                  <p class=\"description\">\n\t                    \tHo usato i modelli per ottenere del know-how per il mio lavoro. Sulla questa base ho preparato la mia metodologia. Grazie.\t                  <\/p>\n                               \n            <\/div>\n                      \n         <\/div>\n      \n         <div class=\"card\">               \n               \n            \n            <div class=\"card-content\">\n               <h3 class=\"card-title h5\">\n\t\t            \t\t              \tDarren Pulman\t\t                           <\/h3>\n\t\t\t\t\t\t\t                  <p class=\"description\">\n\t                    \tIl kit ha aiutato a chiarire i requisiti della norma e ha davvero aiutato ad accelerare il processo di creazione dei documenti.\t                  <\/p>\n                               \n            <\/div>\n                      \n         <\/div>\n      \n         <div class=\"card\">               \n               \n            \n            <div class=\"card-content\">\n               <h3 class=\"card-title h5\">\n\t\t            \t\t              \tJohn Salvatore\t\t                           <\/h3>\n\t\t\t\t\t\t\t                  <p class=\"description\">\n\t                    \tNon avevo idea di dove iniziare, come organizzare il progetto e quali fossero i requisiti reali e le decisioni da prendere. Il kit \u00e8 stato inestimabile per me.\t                  <\/p>\n                               \n            <\/div>\n                      \n         <\/div>\n      \t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-5\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-faq siteorigin-panels-stretch top-padding-xs bottom-padding-xs panel-row-style panel-row-style-for-87832-5\" data-stretch-type=\"full\" ><div id=\"pgc-87832-5-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-5-0-0\" class=\"so-panel widget widget_adv_display_site_element panel-first-child panel-last-child\" data-index=\"9\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_display_site_element so-widget-adv_display_site_element-base\"\n\t\t\t\n\t\t><div class=\"site_element-wrap\"><div id=\"pl-86823\"  class=\"panel-layout\" ><div id=\"pg-86823-0\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch top-padding-s panel-row-style panel-row-style-for-86823-0\" data-stretch-type=\"full\" ><div id=\"pgc-86823-0-0\"  class=\"panel-grid-cell panel-grid-cell-mobile-last\" ><div id=\"panel-86823-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2>Domande Frequenti<\/h2>\n<p>Non hai trovato la risposta? Dai un\u2019occhiata alle nostre FAQ. Questa sezione di facile utilizzo ti aiuter\u00e0 a trovare le risposte alle domande pi\u00f9 frequenti.<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-86823-0-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><div id=\"pg-86823-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-86823-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-86823-1-0-0\" class=\"so-panel widget widget_adv_accordion panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_accordion so-widget-adv_accordion-base\"\n\t\t\t\n\t\t><section class=\"adv-accordion adv-new-style\">\n  \n  \n  <div class=\"accordion-wrap\">\n  \t\t\n  \t\t\t\t\t\n\t\t\t\t<div class=\"acc-column\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"panel\">\n\t\t\t\t\t\t\t<div class=\"panel-nav\">\n\t\t\t\t\t\t\t\t<h5 class=\"h7 panel-title\">Come ricever\u00f2 il modello?<\/h5>\n\t\t\t\t\t\t\t\t<button class=\"acc-toggle\"><i class=\"icon icon-caret icon-arr-down\"><\/i><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"panel-content\">\n\t\t\t\t\t\t\t\t<p>Dopo la conferma del pagamento, ti invieremo un'email contenente un link per scaricare il documento. \u00c8 super facile.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"panel\">\n\t\t\t\t\t\t\t<div class=\"panel-nav\">\n\t\t\t\t\t\t\t\t<h5 class=\"h7 panel-title\">Che tipo di pagamento accettate?<\/h5>\n\t\t\t\t\t\t\t\t<button class=\"acc-toggle\"><i class=\"icon icon-caret icon-arr-down\"><\/i><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"panel-content\">\n\t\t\t\t\t\t\t\t<p>\u00c8 possibile pagare con le principali carte di credito o tramite bonifico dal proprio conto bancario.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"panel\">\n\t\t\t\t\t\t\t<div class=\"panel-nav\">\n\t\t\t\t\t\t\t\t<h5 class=\"h7 panel-title\">Come proteggete i miei dati di pagamento?<\/h5>\n\t\t\t\t\t\t\t\t<button class=\"acc-toggle\"><i class=\"icon icon-caret icon-arr-down\"><\/i><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"panel-content\">\n\t\t\t\t\t\t\t\t<p>Usiamo la tecnologia Secure Socket Layer (SSL), che \u00e8 lo standard del settore ed \u00e8 considerato uno dei sistemi pi\u00f9 sicuri per il pagamento online. I dati del tuo conto e della tua carta di credito sono criptati e vanno direttamente al processore di pagamento. Noi non avremo accesso ai tuoi dati di pagamento n\u00e9 li archivieremo in alcun modo.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"panel\">\n\t\t\t\t\t\t\t<div class=\"panel-nav\">\n\t\t\t\t\t\t\t\t<h5 class=\"h7 panel-title\">Quali valute accettate?<\/h5>\n\t\t\t\t\t\t\t\t<button class=\"acc-toggle\"><i class=\"icon icon-caret icon-arr-down\"><\/i><\/button>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"panel-content\">\n\t\t\t\t\t\t\t\t<p>Accettiamo pagamenti in oltre 50 tra le valute pi\u00f9 comuni, inclusi Franchi svizzeri, Dollari americani, Sterline inglesi ed Euro.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\n\t\t\n\t\t\t\t\t\t\t\n\n\t\t\t\t\n\n\t\t<\/div>\n\t<\/section>\n\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div id=\"pg-87832-6\"  class=\"panel-grid panel-has-style\" ><div class=\"toolkit-documents-cta panel-row-style panel-row-style-for-87832-6\" ><div id=\"pgc-87832-6-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87832-6-0-0\" class=\"so-panel widget widget_adv_display_site_element panel-first-child panel-last-child\" data-index=\"10\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_display_site_element so-widget-adv_display_site_element-base\"\n\t\t\t\n\t\t><div class=\"site_element-wrap\"><div id=\"pl-87461\"  class=\"panel-layout\" ><div id=\"pg-87461-0\"  class=\"panel-grid panel-has-style\" ><div class=\"text-light siteorigin-panels-stretch top-padding-s bottom-padding-s cta-section panel-row-style panel-row-style-for-87461-0\" data-stretch-type=\"full\" ><div id=\"pgc-87461-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-87461-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 class=\"h1-m\">Pianifica una Presentazione Gratuita<\/h2>\n<p>Hai bisogno di assistenza? Contattaci ora. Ti risponderemo rapidamente.<\/p>\n<\/div>\n<\/div><\/div><\/div><div id=\"pgc-87461-0-1\"  class=\"panel-grid-cell\" ><div id=\"panel-87461-0-1-0\" class=\"so-panel widget widget_adv_buttons panel-first-child panel-last-child\" data-index=\"1\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-adv_buttons so-widget-adv_buttons-base\"\n\t\t\t\n\t\t>\t<a class=\"btn push-campaign-utms btn-cta\" href=\"https:\/\/advisera.com\/schedule-meeting\/\" target=\"_blank\" aria-label=\"Prenota ora\">\r\n\t\tPrenota ora\t<\/a>\r\n\r\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Modello di documento GDPR dell&#8217;UE: Registro delle Valutazioni d\u2019Impatto sulla Protezione dei Dati Un documento utilizzato dalle aziende per documentare [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","class_list":["post-87832","adv_documents","type-adv_documents","status-publish","hentry","adv_resource_type-toolkit-documents-it","adv_standard-eu-gdpr-it","adv_toolkit_type-eu-gdpr-premium-documentation-toolkit-it","adv_toolkit_type-eu-gdpr-documentation-toolkit-it","adv_toolkit_type-eu-gdpr-data-mapping-dpia-toolkit-it"],"acf":[],"_links":{"self":[{"href":"https:\/\/advisera.com\/it\/wp-json\/wp\/v2\/adv_documents\/87832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/advisera.com\/it\/wp-json\/wp\/v2\/adv_documents"}],"about":[{"href":"https:\/\/advisera.com\/it\/wp-json\/wp\/v2\/types\/adv_documents"}],"version-history":[{"count":0,"href":"https:\/\/advisera.com\/it\/wp-json\/wp\/v2\/adv_documents\/87832\/revisions"}],"wp:attachment":[{"href":"https:\/\/advisera.com\/it\/wp-json\/wp\/v2\/media?parent=87832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}